{"id":10,"date":"2024-10-23T14:29:35","date_gmt":"2024-10-23T21:29:35","guid":{"rendered":"https:\/\/ashleetxads.org\/?page_id=10"},"modified":"2026-05-02T05:00:00","modified_gmt":"2026-05-02T09:00:00","slug":"home","status":"publish","type":"page","link":"https:\/\/hexibella.fr\/es\/?page_id=40","title":{"rendered":"Hogar"},"content":{"rendered":"<style class=\"wpcode-css-snippet\">div.hero-section.is-width-constrained {\r\n\tdisplay:none !important;\r\n}\r\n\r\ndiv.ct-container-full {\r\npadding-top:0px !important;\r\nmargin-top:0px !important;\r\n}\r\n\r\ndiv.blocksy-woo-messages-default.woocommerce-notices-wrapper{\r\n\t\tdisplay:none !important;\r\n}<\/style>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-oeq4519p alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-iknn4edd uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title-prefix\">Desbloquear posibilidades<\/p><h1 class=\"uagb-ifb-title\">Hexibella - Tu mundo<\/h1><\/div><p class=\"uagb-ifb-desc\">Nuestro mundo es un lienzo para que sus ideas m\u00e1s salvajes cobren vida. Entra en un mundo donde tu autoexpresi\u00f3n es nuestro objetivo.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-72njyydx\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-oijirkrz wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/hexibella.com\/category\/womens-fashion\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">COMPRAR AHORA<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-ycbcospq alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-2zwetssz uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><h2 class=\"uagb-ifb-title\">Acerca de Hexibella<\/h2><\/div><p class=\"uagb-ifb-desc\">En Hexibella, nuestra visi\u00f3n es ofrecer productos sorprendentes que reflejen la personalidad de nuestros clientes. Nos dedicamos a inspirar confianza en uno mismo y a sacar al mercado los mejores productos que permitan a nuestros clientes expresarse y mejorar su estilo de vida.<br><br>- <strong>Director ejecutivo de Hexibella<\/strong><br><\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-image alignleft uagb-block-3qqlt31s wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-left\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/hexibella.com\/wp-content\/uploads\/2026\/05\/a-vibrant-abstract-image-featuring-dynamic-colors-and-intricate-patterns-perfect-for-modern-art-enthusiasts.-14367717-1024x683.jpg\" alt=\"Una vibrante imagen abstracta con colores din\u00e1micos y patrones intrincados, perfecta para los entusiastas del arte moderno.\" class=\"uag-image-10182\" width=\"564\" height=\"450\" title=\"Foto de Merlin Lightpainting\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-g5yyuncp alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-info-box uagb-block-txndopju uagb-infobox__content-wrap  uagb-infobox-icon-above-title uagb-infobox-image-valign-top\"><div class=\"uagb-ifb-content\"><div class=\"uagb-ifb-title-wrap\"><p class=\"uagb-ifb-title-prefix\">Mantente conectado con nosotros<\/p><h2 class=\"uagb-ifb-title\">Vamos a crear juntos<\/h2><\/div><p class=\"uagb-ifb-desc\">P\u00f3ngase en contacto con nosotros para ver c\u00f3mo podemos hacer realidad su visi\u00f3n.<\/p><\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-bpuwmdkh\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-0ij9cu6z wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/hexibella.com\/contact-us\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">CONT\u00c1CTENOS<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":15,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"bwfblock_default_font":"","_uag_custom_page_level_css":"","footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"blocksy_meta":{"has_hero_section":"disabled","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":7}},"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"woocommerce_archive_thumbnail":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/hexibella.fr\/es\/author\/admin_v6jhkhci\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":12,"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":10183,"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/pages\/10\/revisions\/10183"}],"wp:attachment":[{"href":"https:\/\/hexibella.fr\/es\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"Gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}